{"id":10009674,"date":"2026-03-16T11:15:23","date_gmt":"2026-03-16T10:15:23","guid":{"rendered":"https:\/\/www.archeoparc.it\/event\/bw-haselnusspfeifchen\/"},"modified":"2026-03-16T11:18:56","modified_gmt":"2026-03-16T10:18:56","slug":"bw-haselnusspfeifchen","status":"publish","type":"tribe_events","link":"https:\/\/www.archeoparc.it\/en\/event\/bw-haselnusspfeifchen\/2026-06-09\/","title":{"rendered":"Whistle making workshop"},"content":{"rendered":"<div  class=\"tribe-events-schedule tribe-clearfix\" >\n\t<p class=\"tribe-events-schedule__datetime\">\n\t\t<span class=\"tribe-events-schedule__date tribe-events-schedule__date--start\">\n\t\t\t9. June\t\t<\/span>\n\n\t\t\t\t\t<span class=\"tribe-events-schedule__separator tribe-events-schedule__separator--date\">\n\t\t\t\t &#8211; \t\t\t<\/span>\n\t\t\t<span class=\"tribe-events-schedule__time tribe-events-schedule__time--start\">\n\t\t\t\t12:30\t\t\t<\/span>\n\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"tribe-events-schedule__separator tribe-events-schedule__separator--time\">\n\t\t\t\t\t &#8211; \t\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"tribe-events-schedule__time tribe-events-schedule__time--end\">\n\t\t\t\t\t16:30\t\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t<\/p>\n<\/div>\n\n\n\n<p>When it was that humans began making noises with their bodies, we do not know. Musical instruments such as whistles, flutes, rattles, and drums go back approximately forty thousand years. Under the instruction of our museum educators, you can use flint and sandstone to make a whistle out of a hazelnut shell, as was done back as early as the Stone Age.<\/p>\n\n\n\n<p>No registration required | Starts several times from 12:30 on | Included in the admission fee | Course 2 | Workshop area (#09) | Duration: 40-60 min | Last entrance for visiting all hands-on areas at 14:00<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>When it was that humans began making noises with their bodies, we do not know. Musical instruments such as whistles, flutes, rattles, and drums go back approximately forty thousand years. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":14235,"template":"","meta":{"_acf_changed":false,"_tec_requires_first_save":false,"_EventAllDay":false,"_EventTimezone":"Europe\/Rome","_EventStartDate":"2026-06-09 12:30:00","_EventEndDate":"2026-06-09 16:30:00","_EventStartDateUTC":"2026-06-09 10:30:00","_EventEndDateUTC":"2026-06-09 14:30:00","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"\u20ac","_EventCurrencyCode":"USD","_EventCurrencyPosition":"prefix","_EventDateTimeSeparator":" - ","_EventTimeRangeSeparator":" - ","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_blocks_recurrence_rules":"[{\"type\":\"single\",\"all_day\":false,\"multi_day\":false,\"start_date\":\"2026-04-10\",\"_start_date_input\":\"10.04.2026\",\"_start_date_obj\":\"2026-04-09T22:00:00.000Z\",\"start_time\":\"12:30:00\",\"_start_time_input\":\"12:30\",\"end_date\":\"2026-04-09\",\"_end_date_input\":\"09.04.2026\",\"_end_date_obj\":\"2026-09-03T22:00:00.000Z\",\"end_time\":\"16:30:00\",\"_end_time_input\":\"16:30\",\"between\":1,\"limit_type\":\"never\",\"limit\":10,\"_limit_date_input\":\"16.03.2027\",\"_limit_date_obj\":null,\"days\":[4],\"week\":\"second\",\"day\":4,\"month\":[4],\"timezone\":\"Europe\/Rome\",\"multi_day_span\":\"next_day\",\"isOffStart\":false},{\"type\":\"single\",\"all_day\":false,\"multi_day\":false,\"start_date\":\"2026-05-08\",\"_start_date_input\":\"08.05.2026\",\"_start_date_obj\":\"2026-05-07T22:00:00.000Z\",\"start_time\":\"12:30:00\",\"_start_time_input\":\"12:30\",\"end_date\":\"2026-04-09\",\"_end_date_input\":\"09.04.2026\",\"_end_date_obj\":\"2026-09-03T22:00:00.000Z\",\"end_time\":\"16:30:00\",\"_end_time_input\":\"16:30\",\"between\":1,\"limit_type\":\"never\",\"limit\":10,\"_limit_date_input\":\"16.03.2027\",\"_limit_date_obj\":null,\"days\":[4],\"week\":\"second\",\"day\":4,\"month\":[4],\"timezone\":\"Europe\/Rome\",\"multi_day_span\":\"next_day\",\"isOffStart\":false},{\"type\":\"single\",\"all_day\":false,\"multi_day\":false,\"start_date\":\"2026-05-09\",\"_start_date_input\":\"09.05.2026\",\"_start_date_obj\":\"2026-05-08T22:00:00.000Z\",\"start_time\":\"12:30:00\",\"_start_time_input\":\"12:30\",\"end_date\":\"2026-04-09\",\"_end_date_input\":\"09.04.2026\",\"_end_date_obj\":\"2026-09-03T22:00:00.000Z\",\"end_time\":\"16:30:00\",\"_end_time_input\":\"16:30\",\"between\":1,\"limit_type\":\"never\",\"limit\":10,\"_limit_date_input\":\"16.03.2027\",\"_limit_date_obj\":null,\"days\":[4],\"week\":\"second\",\"day\":4,\"month\":[4],\"timezone\":\"Europe\/Rome\",\"multi_day_span\":\"next_day\",\"isOffStart\":false},{\"type\":\"single\",\"all_day\":false,\"multi_day\":false,\"start_date\":\"2026-05-10\",\"_start_date_input\":\"10.05.2026\",\"_start_date_obj\":\"2026-05-09T22:00:00.000Z\",\"start_time\":\"12:30:00\",\"_start_time_input\":\"12:30\",\"end_date\":\"2026-04-09\",\"_end_date_input\":\"09.04.2026\",\"_end_date_obj\":\"2026-09-03T22:00:00.000Z\",\"end_time\":\"16:30:00\",\"_end_time_input\":\"16:30\",\"between\":1,\"limit_type\":\"never\",\"limit\":10,\"_limit_date_input\":\"16.03.2027\",\"_limit_date_obj\":null,\"days\":[4],\"week\":\"second\",\"day\":4,\"month\":[4],\"timezone\":\"Europe\/Rome\",\"multi_day_span\":\"next_day\",\"isOffStart\":false},{\"type\":\"single\",\"all_day\":false,\"multi_day\":false,\"start_date\":\"2026-05-11\",\"_start_date_input\":\"11.05.2026\",\"_start_date_obj\":\"2026-05-10T22:00:00.000Z\",\"start_time\":\"12:30:00\",\"_start_time_input\":\"12:30\",\"end_date\":\"2026-04-09\",\"_end_date_input\":\"09.04.2026\",\"_end_date_obj\":\"2026-09-03T22:00:00.000Z\",\"end_time\":\"16:30:00\",\"_end_time_input\":\"16:30\",\"between\":1,\"limit_type\":\"never\",\"limit\":10,\"_limit_date_input\":\"16.03.2027\",\"_limit_date_obj\":null,\"days\":[4],\"week\":\"second\",\"day\":4,\"month\":[4],\"timezone\":\"Europe\/Rome\",\"multi_day_span\":\"next_day\",\"isOffStart\":false},{\"type\":\"single\",\"all_day\":false,\"multi_day\":false,\"start_date\":\"2026-06-08\",\"_start_date_input\":\"08.06.2026\",\"_start_date_obj\":\"2026-06-07T22:00:00.000Z\",\"start_time\":\"12:30:00\",\"_start_time_input\":\"12:30\",\"end_date\":\"2026-04-09\",\"_end_date_input\":\"09.04.2026\",\"_end_date_obj\":\"2026-09-03T22:00:00.000Z\",\"end_time\":\"16:30:00\",\"_end_time_input\":\"16:30\",\"between\":1,\"limit_type\":\"never\",\"limit\":10,\"_limit_date_input\":\"16.03.2027\",\"_limit_date_obj\":null,\"days\":[4],\"week\":\"second\",\"day\":4,\"month\":[4],\"timezone\":\"Europe\/Rome\",\"multi_day_span\":\"next_day\",\"isOffStart\":false},{\"type\":\"single\",\"all_day\":false,\"multi_day\":false,\"start_date\":\"2026-06-09\",\"_start_date_input\":\"09.06.2026\",\"_start_date_obj\":\"2026-06-08T22:00:00.000Z\",\"start_time\":\"12:30:00\",\"_start_time_input\":\"12:30\",\"end_date\":\"2026-04-09\",\"_end_date_input\":\"09.04.2026\",\"_end_date_obj\":\"2026-09-03T22:00:00.000Z\",\"end_time\":\"16:30:00\",\"_end_time_input\":\"16:30\",\"between\":1,\"limit_type\":\"never\",\"limit\":10,\"_limit_date_input\":\"16.03.2027\",\"_limit_date_obj\":null,\"days\":[4],\"week\":\"second\",\"day\":4,\"month\":[4],\"timezone\":\"Europe\/Rome\",\"multi_day_span\":\"next_day\",\"isOffStart\":false},{\"type\":\"single\",\"all_day\":false,\"multi_day\":false,\"start_date\":\"2026-06-10\",\"_start_date_input\":\"10.06.2026\",\"_start_date_obj\":\"2026-06-09T22:00:00.000Z\",\"start_time\":\"12:30:00\",\"_start_time_input\":\"12:30\",\"end_date\":\"2026-04-09\",\"_end_date_input\":\"09.04.2026\",\"_end_date_obj\":\"2026-09-03T22:00:00.000Z\",\"end_time\":\"16:30:00\",\"_end_time_input\":\"16:30\",\"between\":1,\"limit_type\":\"never\",\"limit\":10,\"_limit_date_input\":\"16.03.2027\",\"_limit_date_obj\":null,\"days\":[4],\"week\":\"second\",\"day\":4,\"month\":[4],\"timezone\":\"Europe\/Rome\",\"multi_day_span\":\"next_day\",\"isOffStart\":false},{\"type\":\"single\",\"all_day\":false,\"multi_day\":false,\"start_date\":\"2026-10-13\",\"_start_date_input\":\"13.10.2026\",\"_start_date_obj\":\"2026-10-12T22:00:00.000Z\",\"start_time\":\"12:30:00\",\"_start_time_input\":\"12:30\",\"end_date\":\"2026-04-09\",\"_end_date_input\":\"09.04.2026\",\"_end_date_obj\":\"2026-09-03T22:00:00.000Z\",\"end_time\":\"16:30:00\",\"_end_time_input\":\"16:30\",\"between\":1,\"limit_type\":\"never\",\"limit\":10,\"_limit_date_input\":\"16.03.2027\",\"_limit_date_obj\":null,\"days\":[4],\"week\":\"second\",\"day\":4,\"month\":[4],\"timezone\":\"Europe\/Rome\",\"multi_day_span\":\"next_day\",\"isOffStart\":false},{\"type\":\"single\",\"all_day\":false,\"multi_day\":false,\"start_date\":\"2026-10-14\",\"_start_date_input\":\"14.10.2026\",\"_start_date_obj\":\"2026-10-13T22:00:00.000Z\",\"start_time\":\"12:30:00\",\"_start_time_input\":\"12:30\",\"end_date\":\"2026-04-09\",\"_end_date_input\":\"09.04.2026\",\"_end_date_obj\":\"2026-09-03T22:00:00.000Z\",\"end_time\":\"16:30:00\",\"_end_time_input\":\"16:30\",\"between\":1,\"limit_type\":\"never\",\"limit\":10,\"_limit_date_input\":\"16.03.2027\",\"_limit_date_obj\":null,\"days\":[4],\"week\":\"second\",\"day\":4,\"month\":[4],\"timezone\":\"Europe\/Rome\",\"multi_day_span\":\"next_day\",\"isOffStart\":false},{\"type\":\"single\",\"all_day\":false,\"multi_day\":false,\"start_date\":\"2026-10-15\",\"_start_date_input\":\"15.10.2026\",\"_start_date_obj\":\"2026-10-14T22:00:00.000Z\",\"start_time\":\"12:30:00\",\"_start_time_input\":\"12:30\",\"end_date\":\"2026-04-09\",\"_end_date_input\":\"09.04.2026\",\"_end_date_obj\":\"2026-09-03T22:00:00.000Z\",\"end_time\":\"16:30:00\",\"_end_time_input\":\"16:30\",\"between\":1,\"limit_type\":\"never\",\"limit\":10,\"_limit_date_input\":\"16.03.2027\",\"_limit_date_obj\":null,\"days\":[4],\"week\":\"second\",\"day\":4,\"month\":[4],\"timezone\":\"Europe\/Rome\",\"multi_day_span\":\"next_day\",\"isOffStart\":false},{\"type\":\"single\",\"all_day\":false,\"multi_day\":false,\"start_date\":\"2026-10-16\",\"_start_date_input\":\"16.10.2026\",\"_start_date_obj\":\"2026-10-15T22:00:00.000Z\",\"start_time\":\"12:30:00\",\"_start_time_input\":\"12:30\",\"end_date\":\"2026-04-09\",\"_end_date_input\":\"09.04.2026\",\"_end_date_obj\":\"2026-09-03T22:00:00.000Z\",\"end_time\":\"16:30:00\",\"_end_time_input\":\"16:30\",\"between\":1,\"limit_type\":\"never\",\"limit\":10,\"_limit_date_input\":\"16.03.2027\",\"_limit_date_obj\":null,\"days\":[4],\"week\":\"second\",\"day\":4,\"month\":[4],\"timezone\":\"Europe\/Rome\",\"multi_day_span\":\"next_day\",\"isOffStart\":false},{\"type\":\"single\",\"all_day\":false,\"multi_day\":false,\"start_date\":\"2026-11-05\",\"_start_date_input\":\"05.11.2026\",\"_start_date_obj\":\"2026-11-04T23:00:00.000Z\",\"start_time\":\"12:30:00\",\"_start_time_input\":\"12:30\",\"end_date\":\"2026-04-09\",\"_end_date_input\":\"09.04.2026\",\"_end_date_obj\":\"2026-09-03T22:00:00.000Z\",\"end_time\":\"16:30:00\",\"_end_time_input\":\"16:30\",\"between\":1,\"limit_type\":\"never\",\"limit\":10,\"_limit_date_input\":\"16.03.2027\",\"_limit_date_obj\":null,\"days\":[4],\"week\":\"second\",\"day\":4,\"month\":[4],\"timezone\":\"Europe\/Rome\",\"multi_day_span\":\"next_day\",\"isOffStart\":false},{\"type\":\"single\",\"all_day\":false,\"multi_day\":false,\"start_date\":\"2026-11-06\",\"_start_date_input\":\"06.11.2026\",\"_start_date_obj\":\"2026-11-05T23:00:00.000Z\",\"start_time\":\"12:30:00\",\"_start_time_input\":\"12:30\",\"end_date\":\"2026-04-09\",\"_end_date_input\":\"09.04.2026\",\"_end_date_obj\":\"2026-09-03T22:00:00.000Z\",\"end_time\":\"16:30:00\",\"_end_time_input\":\"16:30\",\"between\":1,\"limit_type\":\"never\",\"limit\":10,\"_limit_date_input\":\"16.03.2027\",\"_limit_date_obj\":null,\"days\":[4],\"week\":\"second\",\"day\":4,\"month\":[4],\"timezone\":\"Europe\/Rome\",\"multi_day_span\":\"next_day\",\"isOffStart\":false}]","_tribe_blocks_recurrence_description":"","_tribe_blocks_recurrence_exclusions":"","_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[936],"tribe_events_cat":[992,1015,277,281,317,309],"class_list":["post-10009674","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-kalender-mitmachangebote","tribe_events_cat-kalender-mitmachangebote-en","tribe_events_cat-workshop-en","tribe_events_cat-erwachsene-en","tribe_events_cat-kinder-in-begleitung-en","tribe_events_cat-8plus-en","tribe_events_cat-mehrsprachig-en","cat_kalender-mitmachangebote-en","cat_workshop-en","cat_erwachsene-en","cat_kinder-in-begleitung-en","cat_8plus-en","cat_mehrsprachig-en","tribe-recurring-event","tribe-recurring-event-parent"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Whistle making workshop - archeoParc Schnalstal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.archeoparc.it\/en\/event\/bw-haselnusspfeifchen\/2026-06-09\/\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.archeoparc.it\\\/en\\\/event\\\/bw-haselnusspfeifchen\\\/2026-06-09\\\/\",\"url\":\"https:\\\/\\\/www.archeoparc.it\\\/en\\\/event\\\/bw-haselnusspfeifchen\\\/2026-06-09\\\/\",\"name\":\"Whistle making workshop - archeoParc Schnalstal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.archeoparc.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.archeoparc.it\\\/en\\\/event\\\/bw-haselnusspfeifchen\\\/2026-06-09\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.archeoparc.it\\\/en\\\/event\\\/bw-haselnusspfeifchen\\\/2026-06-09\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.archeoparc.it\\\/wp-content\\\/uploads\\\/archeoParc-schnalstal-platzhalter-e1458314677915.jpg\",\"datePublished\":\"2026-03-16T10:15:23+00:00\",\"dateModified\":\"2026-03-16T10:18:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.archeoparc.it\\\/en\\\/event\\\/bw-haselnusspfeifchen\\\/2026-06-09\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.archeoparc.it\\\/en\\\/event\\\/bw-haselnusspfeifchen\\\/2026-06-09\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.archeoparc.it\\\/en\\\/event\\\/bw-haselnusspfeifchen\\\/2026-06-09\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.archeoparc.it\\\/wp-content\\\/uploads\\\/archeoParc-schnalstal-platzhalter-e1458314677915.jpg\",\"contentUrl\":\"https:\\\/\\\/www.archeoparc.it\\\/wp-content\\\/uploads\\\/archeoParc-schnalstal-platzhalter-e1458314677915.jpg\",\"width\":3508,\"height\":2480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.archeoparc.it\\\/en\\\/event\\\/bw-haselnusspfeifchen\\\/2026-06-09\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/www.archeoparc.it\\\/veranstaltungen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Whistle making workshop\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.archeoparc.it\\\/#website\",\"url\":\"https:\\\/\\\/www.archeoparc.it\\\/\",\"name\":\"archeoParc Schnalstal\",\"description\":\"Arch\u00e4ologisches Freilichtmuseum\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.archeoparc.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.archeoparc.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.archeoparc.it\\\/#organization\",\"name\":\"archeoparc Schnalstal\",\"url\":\"https:\\\/\\\/www.archeoparc.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.archeoparc.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.archeoparc.it\\\/wp-content\\\/uploads\\\/cropped-archeoparc_logo_sw.png\",\"contentUrl\":\"https:\\\/\\\/www.archeoparc.it\\\/wp-content\\\/uploads\\\/cropped-archeoparc_logo_sw.png\",\"width\":654,\"height\":211,\"caption\":\"archeoparc Schnalstal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.archeoparc.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Whistle making workshop - archeoParc Schnalstal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.archeoparc.it\/en\/event\/bw-haselnusspfeifchen\/2026-06-09\/","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.archeoparc.it\/en\/event\/bw-haselnusspfeifchen\/2026-06-09\/","url":"https:\/\/www.archeoparc.it\/en\/event\/bw-haselnusspfeifchen\/2026-06-09\/","name":"Whistle making workshop - archeoParc Schnalstal","isPartOf":{"@id":"https:\/\/www.archeoparc.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.archeoparc.it\/en\/event\/bw-haselnusspfeifchen\/2026-06-09\/#primaryimage"},"image":{"@id":"https:\/\/www.archeoparc.it\/en\/event\/bw-haselnusspfeifchen\/2026-06-09\/#primaryimage"},"thumbnailUrl":"https:\/\/www.archeoparc.it\/wp-content\/uploads\/archeoParc-schnalstal-platzhalter-e1458314677915.jpg","datePublished":"2026-03-16T10:15:23+00:00","dateModified":"2026-03-16T10:18:56+00:00","breadcrumb":{"@id":"https:\/\/www.archeoparc.it\/en\/event\/bw-haselnusspfeifchen\/2026-06-09\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.archeoparc.it\/en\/event\/bw-haselnusspfeifchen\/2026-06-09\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.archeoparc.it\/en\/event\/bw-haselnusspfeifchen\/2026-06-09\/#primaryimage","url":"https:\/\/www.archeoparc.it\/wp-content\/uploads\/archeoParc-schnalstal-platzhalter-e1458314677915.jpg","contentUrl":"https:\/\/www.archeoparc.it\/wp-content\/uploads\/archeoParc-schnalstal-platzhalter-e1458314677915.jpg","width":3508,"height":2480},{"@type":"BreadcrumbList","@id":"https:\/\/www.archeoparc.it\/en\/event\/bw-haselnusspfeifchen\/2026-06-09\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Veranstaltungen","item":"https:\/\/www.archeoparc.it\/veranstaltungen\/"},{"@type":"ListItem","position":2,"name":"Whistle making workshop"}]},{"@type":"WebSite","@id":"https:\/\/www.archeoparc.it\/#website","url":"https:\/\/www.archeoparc.it\/","name":"archeoParc Schnalstal","description":"Arch\u00e4ologisches Freilichtmuseum","publisher":{"@id":"https:\/\/www.archeoparc.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.archeoparc.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.archeoparc.it\/#organization","name":"archeoparc Schnalstal","url":"https:\/\/www.archeoparc.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.archeoparc.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.archeoparc.it\/wp-content\/uploads\/cropped-archeoparc_logo_sw.png","contentUrl":"https:\/\/www.archeoparc.it\/wp-content\/uploads\/cropped-archeoparc_logo_sw.png","width":654,"height":211,"caption":"archeoparc Schnalstal"},"image":{"@id":"https:\/\/www.archeoparc.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.archeoparc.it\/en\/wp-json\/wp\/v2\/tribe_events\/10009674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.archeoparc.it\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.archeoparc.it\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.archeoparc.it\/en\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":0,"href":"https:\/\/www.archeoparc.it\/en\/wp-json\/wp\/v2\/tribe_events\/10009674\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.archeoparc.it\/en\/wp-json\/wp\/v2\/media\/14235"}],"wp:attachment":[{"href":"https:\/\/www.archeoparc.it\/en\/wp-json\/wp\/v2\/media?parent=10009674"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.archeoparc.it\/en\/wp-json\/wp\/v2\/tags?post=10009674"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.archeoparc.it\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=10009674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}