{"id":10016831,"date":"2026-05-11T16:40:18","date_gmt":"2026-05-11T14:40:18","guid":{"rendered":"https:\/\/www.archeoparc.it\/event\/jt-stockbrot\/"},"modified":"2026-05-11T16:43:32","modified_gmt":"2026-05-11T14:43:32","slug":"jt-stockbrot","status":"publish","type":"tribe_events","link":"https:\/\/www.archeoparc.it\/en\/event\/jt-stockbrot\/2026-07-15\/","title":{"rendered":"Bread baking on a stick"},"content":{"rendered":"<div  class=\"tribe-events-schedule tribe-clearfix\" >\n\t<p class=\"tribe-events-schedule__datetime\">\n\t\t<span class=\"tribe-events-schedule__date tribe-events-schedule__date--start\">\n\t\t\t15. July\t\t<\/span>\n\n\t\t\t\t\t<span class=\"tribe-events-schedule__separator tribe-events-schedule__separator--date\">\n\t\t\t\t &#8211; \t\t\t<\/span>\n\t\t\t<span class=\"tribe-events-schedule__time tribe-events-schedule__time--start\">\n\t\t\t\t12:30\t\t\t<\/span>\n\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"tribe-events-schedule__separator tribe-events-schedule__separator--time\">\n\t\t\t\t\t &#8211; \t\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"tribe-events-schedule__time tribe-events-schedule__time--end\">\n\t\t\t\t\t16:30\t\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t<\/p>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">In the workshop area of the archeoParc, visitors can bake bread on a stick over the embers of a campfire every day. A grain dough is provided and, once shaped around the sticks, it is baked directly in the embers.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No registration required | Starts every hour from 12:30 on, last start one hour before the evening closing of the open-air area | Included in the admission fee | Workshop area (#09 ) | Course 2 | Duration: approx. 20 min | Does not take place on days with free admission | We recommend wearing clothes that can get dirty | Takes place under the umbrella roof of the workshop area in case of rain | Last admission for visiting all areas and adventure stations at 14:00<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In the workshop area of the archeoParc, visitors can bake bread on a stick over the embers of a campfire every day. A grain dough is provided and, once shaped [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":20413,"template":"","meta":{"_acf_changed":false,"_tec_requires_first_save":false,"_EventAllDay":false,"_EventTimezone":"Europe\/Rome","_EventStartDate":"2026-07-15 12:30:00","_EventEndDate":"2026-07-15 16:30:00","_EventStartDateUTC":"2026-07-15 10:30:00","_EventEndDateUTC":"2026-07-15 14:30:00","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"\u20ac","_EventCurrencyCode":"USD","_EventCurrencyPosition":"prefix","_EventDateTimeSeparator":" - ","_EventTimeRangeSeparator":" - ","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_blocks_recurrence_rules":"[{\"all_day\":false,\"multi_day\":false,\"type\":\"daily\",\"limit_type\":\"date\",\"limit\":\"2026-11-09\",\"_limit_date_input\":\"November 9, 2026\",\"between\":1,\"start_time\":\"12:30:00\",\"end_time\":\"16:30:00\",\"isOffStart\":false}]","_tribe_blocks_recurrence_description":"","_tribe_blocks_recurrence_exclusions":"[{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"12:30:00\",\"end_time\":\"16:30:00\",\"start_date\":\"2026-06-15\",\"_start_date_input\":\"June 15, 2026\",\"_start_time_input\":\"12:30\",\"_end_time_input\":\"16:30\",\"isOffStart\":false},{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"12:30:00\",\"end_time\":\"16:30:00\",\"start_date\":\"2026-06-16\",\"_start_date_input\":\"June 16, 2026\",\"_start_time_input\":\"12:30\",\"_end_time_input\":\"16:30\",\"isOffStart\":false},{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"12:30:00\",\"end_time\":\"16:30:00\",\"start_date\":\"2026-06-17\",\"_start_date_input\":\"June 17, 2026\",\"_start_time_input\":\"12:30\",\"_end_time_input\":\"16:30\",\"isOffStart\":false},{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"12:30:00\",\"end_time\":\"16:30:00\",\"start_date\":\"2026-06-18\",\"_start_date_input\":\"June 18, 2026\",\"_start_time_input\":\"12:30\",\"_end_time_input\":\"16:30\",\"isOffStart\":false},{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"12:30:00\",\"end_time\":\"16:30:00\",\"start_date\":\"2026-06-19\",\"_start_date_input\":\"June 19, 2026\",\"_start_time_input\":\"12:30\",\"_end_time_input\":\"16:30\",\"isOffStart\":false},{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"12:30:00\",\"end_time\":\"16:30:00\",\"start_date\":\"2026-06-20\",\"_start_date_input\":\"June 20, 2026\",\"_start_time_input\":\"12:30\",\"_end_time_input\":\"16:30\",\"isOffStart\":false},{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"12:30:00\",\"end_time\":\"16:30:00\",\"start_date\":\"2026-06-21\",\"_start_date_input\":\"June 21, 2026\",\"_start_time_input\":\"12:30\",\"_end_time_input\":\"16:30\",\"isOffStart\":false},{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"12:30:00\",\"end_time\":\"16:30:00\",\"start_date\":\"2026-06-22\",\"_start_date_input\":\"June 22, 2026\",\"_start_time_input\":\"12:30\",\"_end_time_input\":\"16:30\",\"isOffStart\":false},{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"12:30:00\",\"end_time\":\"16:30:00\",\"start_date\":\"2026-06-23\",\"_start_date_input\":\"June 23, 2026\",\"_start_time_input\":\"12:30\",\"_end_time_input\":\"16:30\",\"isOffStart\":false},{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"12:30:00\",\"end_time\":\"16:30:00\",\"start_date\":\"2026-06-24\",\"_start_date_input\":\"June 24, 2026\",\"_start_time_input\":\"12:30\",\"_end_time_input\":\"16:30\",\"isOffStart\":false},{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"12:30:00\",\"end_time\":\"16:30:00\",\"start_date\":\"2026-06-25\",\"_start_date_input\":\"June 25, 2026\",\"_start_time_input\":\"12:30\",\"_end_time_input\":\"16:30\",\"isOffStart\":false},{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"12:30:00\",\"end_time\":\"16:30:00\",\"start_date\":\"2026-06-26\",\"_start_date_input\":\"June 26, 2026\",\"_start_time_input\":\"12:30\",\"_end_time_input\":\"16:30\",\"isOffStart\":false},{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"12:30:00\",\"end_time\":\"16:30:00\",\"start_date\":\"2026-06-27\",\"_start_date_input\":\"June 27, 2026\",\"_start_time_input\":\"12:30\",\"_end_time_input\":\"16:30\",\"isOffStart\":false},{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"12:30:00\",\"end_time\":\"16:30:00\",\"start_date\":\"2026-06-28\",\"_start_date_input\":\"June 28, 2026\",\"_start_time_input\":\"12:30\",\"_end_time_input\":\"16:30\",\"isOffStart\":false},{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"12:30:00\",\"end_time\":\"16:30:00\",\"start_date\":\"2026-06-29\",\"_start_date_input\":\"June 29, 2026\",\"_start_time_input\":\"12:30\",\"_end_time_input\":\"16:30\",\"isOffStart\":false},{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"12:30:00\",\"end_time\":\"16:30:00\",\"start_date\":\"2026-06-30\",\"_start_date_input\":\"June 30, 2026\",\"_start_time_input\":\"12:30\",\"_end_time_input\":\"16:30\",\"isOffStart\":false}]","_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[871],"tribe_events_cat":[992,1007,277,281,313,309],"class_list":["post-10016831","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-jt-stockbrot-en","tribe_events_cat-kalender-mitmachangebote-en","tribe_events_cat-keine-anmeldung-en","tribe_events_cat-erwachsene-en","tribe_events_cat-kinder-in-begleitung-en","tribe_events_cat-4plus-en","tribe_events_cat-mehrsprachig-en","cat_kalender-mitmachangebote-en","cat_keine-anmeldung-en","cat_erwachsene-en","cat_kinder-in-begleitung-en","cat_4plus-en","cat_mehrsprachig-en","tribe-recurring-event","tribe-recurring-event-parent"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bread baking on a stick - archeoParc Schnalstal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.archeoparc.it\/en\/event\/jt-stockbrot\/2026-07-15\/\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.archeoparc.it\\\/en\\\/event\\\/jt-stockbrot\\\/2026-07-15\\\/\",\"url\":\"https:\\\/\\\/www.archeoparc.it\\\/en\\\/event\\\/jt-stockbrot\\\/2026-07-15\\\/\",\"name\":\"Bread baking on a stick - archeoParc Schnalstal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.archeoparc.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.archeoparc.it\\\/en\\\/event\\\/jt-stockbrot\\\/2026-07-15\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.archeoparc.it\\\/en\\\/event\\\/jt-stockbrot\\\/2026-07-15\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.archeoparc.it\\\/wp-content\\\/uploads\\\/archeoparc-schnalstal-19021-1.jpg\",\"datePublished\":\"2026-05-11T14:40:18+00:00\",\"dateModified\":\"2026-05-11T14:43:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.archeoparc.it\\\/en\\\/event\\\/jt-stockbrot\\\/2026-07-15\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.archeoparc.it\\\/en\\\/event\\\/jt-stockbrot\\\/2026-07-15\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.archeoparc.it\\\/en\\\/event\\\/jt-stockbrot\\\/2026-07-15\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.archeoparc.it\\\/wp-content\\\/uploads\\\/archeoparc-schnalstal-19021-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.archeoparc.it\\\/wp-content\\\/uploads\\\/archeoparc-schnalstal-19021-1.jpg\",\"width\":5386,\"height\":3591},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.archeoparc.it\\\/en\\\/event\\\/jt-stockbrot\\\/2026-07-15\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/www.archeoparc.it\\\/veranstaltungen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bread baking on a stick\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.archeoparc.it\\\/#website\",\"url\":\"https:\\\/\\\/www.archeoparc.it\\\/\",\"name\":\"archeoParc Schnalstal\",\"description\":\"Arch\u00e4ologisches Freilichtmuseum\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.archeoparc.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.archeoparc.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.archeoparc.it\\\/#organization\",\"name\":\"archeoparc Schnalstal\",\"url\":\"https:\\\/\\\/www.archeoparc.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.archeoparc.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.archeoparc.it\\\/wp-content\\\/uploads\\\/cropped-archeoparc_logo_sw.png\",\"contentUrl\":\"https:\\\/\\\/www.archeoparc.it\\\/wp-content\\\/uploads\\\/cropped-archeoparc_logo_sw.png\",\"width\":654,\"height\":211,\"caption\":\"archeoparc Schnalstal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.archeoparc.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bread baking on a stick - archeoParc Schnalstal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.archeoparc.it\/en\/event\/jt-stockbrot\/2026-07-15\/","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.archeoparc.it\/en\/event\/jt-stockbrot\/2026-07-15\/","url":"https:\/\/www.archeoparc.it\/en\/event\/jt-stockbrot\/2026-07-15\/","name":"Bread baking on a stick - archeoParc Schnalstal","isPartOf":{"@id":"https:\/\/www.archeoparc.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.archeoparc.it\/en\/event\/jt-stockbrot\/2026-07-15\/#primaryimage"},"image":{"@id":"https:\/\/www.archeoparc.it\/en\/event\/jt-stockbrot\/2026-07-15\/#primaryimage"},"thumbnailUrl":"https:\/\/www.archeoparc.it\/wp-content\/uploads\/archeoparc-schnalstal-19021-1.jpg","datePublished":"2026-05-11T14:40:18+00:00","dateModified":"2026-05-11T14:43:32+00:00","breadcrumb":{"@id":"https:\/\/www.archeoparc.it\/en\/event\/jt-stockbrot\/2026-07-15\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.archeoparc.it\/en\/event\/jt-stockbrot\/2026-07-15\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.archeoparc.it\/en\/event\/jt-stockbrot\/2026-07-15\/#primaryimage","url":"https:\/\/www.archeoparc.it\/wp-content\/uploads\/archeoparc-schnalstal-19021-1.jpg","contentUrl":"https:\/\/www.archeoparc.it\/wp-content\/uploads\/archeoparc-schnalstal-19021-1.jpg","width":5386,"height":3591},{"@type":"BreadcrumbList","@id":"https:\/\/www.archeoparc.it\/en\/event\/jt-stockbrot\/2026-07-15\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Veranstaltungen","item":"https:\/\/www.archeoparc.it\/veranstaltungen\/"},{"@type":"ListItem","position":2,"name":"Bread baking on a stick"}]},{"@type":"WebSite","@id":"https:\/\/www.archeoparc.it\/#website","url":"https:\/\/www.archeoparc.it\/","name":"archeoParc Schnalstal","description":"Arch\u00e4ologisches Freilichtmuseum","publisher":{"@id":"https:\/\/www.archeoparc.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.archeoparc.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.archeoparc.it\/#organization","name":"archeoparc Schnalstal","url":"https:\/\/www.archeoparc.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.archeoparc.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.archeoparc.it\/wp-content\/uploads\/cropped-archeoparc_logo_sw.png","contentUrl":"https:\/\/www.archeoparc.it\/wp-content\/uploads\/cropped-archeoparc_logo_sw.png","width":654,"height":211,"caption":"archeoparc Schnalstal"},"image":{"@id":"https:\/\/www.archeoparc.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.archeoparc.it\/en\/wp-json\/wp\/v2\/tribe_events\/10016831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.archeoparc.it\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.archeoparc.it\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.archeoparc.it\/en\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":0,"href":"https:\/\/www.archeoparc.it\/en\/wp-json\/wp\/v2\/tribe_events\/10016831\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.archeoparc.it\/en\/wp-json\/wp\/v2\/media\/20413"}],"wp:attachment":[{"href":"https:\/\/www.archeoparc.it\/en\/wp-json\/wp\/v2\/media?parent=10016831"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.archeoparc.it\/en\/wp-json\/wp\/v2\/tags?post=10016831"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.archeoparc.it\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=10016831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}