{"id":10017803,"date":"2026-05-11T16:58:28","date_gmt":"2026-05-11T14:58:28","guid":{"rendered":"https:\/\/www.archeoparc.it\/event\/demonstration-zum-feuermachen-wie-oetzi\/"},"modified":"2026-05-11T17:00:34","modified_gmt":"2026-05-11T15:00:34","slug":"demonstration-zum-feuermachen-wie-oetzi","status":"publish","type":"tribe_events","link":"https:\/\/www.archeoparc.it\/en\/event\/demonstration-zum-feuermachen-wie-oetzi\/2026-05-13\/","title":{"rendered":"Fire making demonstration"},"content":{"rendered":"<div  class=\"tribe-events-schedule tribe-clearfix\" >\n\t<p class=\"tribe-events-schedule__datetime\">\n\t\t<span class=\"tribe-events-schedule__date tribe-events-schedule__date--start\">\n\t\t\t13. May\t\t<\/span>\n\n\t\t\t\t\t<span class=\"tribe-events-schedule__separator tribe-events-schedule__separator--date\">\n\t\t\t\t &#8211; \t\t\t<\/span>\n\t\t\t<span class=\"tribe-events-schedule__time tribe-events-schedule__time--start\">\n\t\t\t\t11:00\t\t\t<\/span>\n\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"tribe-events-schedule__separator tribe-events-schedule__separator--time\">\n\t\t\t\t\t &#8211; \t\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"tribe-events-schedule__time tribe-events-schedule__time--end\">\n\t\t\t\t\t16:00\t\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t<\/p>\n<\/div>\n\n\n\n<p>Visitors to archeoParc are invited to take part in an expert-led demonstration on how \u00d6tzi made fire using pyrite, flint and tinder fungus.<\/p>\n\n\n\n<p>No registration required | Starts every hour from 11:00 on, last demonstration one hour before the evening closing | Included in the admission fee | House Villanders-Plunacker | Course 1 | Duration: approx. 10 min<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Visitors to archeoParc are invited to take part in an expert-led demonstration on how \u00d6tzi made fire using pyrite, flint and tinder fungus. No registration required | Starts every hour [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":54100,"template":"","meta":{"_acf_changed":false,"_tec_requires_first_save":false,"_EventAllDay":false,"_EventTimezone":"Europe\/Rome","_EventStartDate":"2026-05-13 11:00:00","_EventEndDate":"2026-05-13 16:00:00","_EventStartDateUTC":"2026-05-13 09:00:00","_EventEndDateUTC":"2026-05-13 14:00:00","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"\u20ac","_EventCurrencyCode":"USD","_EventCurrencyPosition":"prefix","_EventDateTimeSeparator":" - ","_EventTimeRangeSeparator":" - ","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_blocks_recurrence_rules":"[{\"all_day\":false,\"multi_day\":false,\"type\":\"daily\",\"limit_type\":\"date\",\"limit\":\"2026-11-09\",\"_limit_date_input\":\"November 9, 2026\",\"between\":1,\"start_time\":\"11:00:00\",\"end_time\":\"16:00:00\",\"isOffStart\":false}]","_tribe_blocks_recurrence_description":"","_tribe_blocks_recurrence_exclusions":"[{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"11:00:00\",\"end_time\":\"16:00:00\",\"start_date\":\"2026-06-15\",\"_start_date_input\":\"June 15, 2026\",\"_start_time_input\":\"11:00\",\"_end_time_input\":\"16:00\",\"isOffStart\":false},{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"11:00:00\",\"end_time\":\"16:00:00\",\"start_date\":\"2026-06-16\",\"_start_date_input\":\"June 16, 2026\",\"_start_time_input\":\"11:00\",\"_end_time_input\":\"16:00\",\"isOffStart\":false},{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"11:00:00\",\"end_time\":\"16:00:00\",\"start_date\":\"2026-06-17\",\"_start_date_input\":\"June 17, 2026\",\"_start_time_input\":\"11:00\",\"_end_time_input\":\"16:00\",\"isOffStart\":false},{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"11:00:00\",\"end_time\":\"16:00:00\",\"start_date\":\"2026-06-18\",\"_start_date_input\":\"June 18, 2026\",\"_start_time_input\":\"11:00\",\"_end_time_input\":\"16:00\",\"isOffStart\":false},{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"11:00:00\",\"end_time\":\"16:00:00\",\"start_date\":\"2026-06-19\",\"_start_date_input\":\"June 19, 2026\",\"_start_time_input\":\"11:00\",\"_end_time_input\":\"16:00\",\"isOffStart\":false},{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"11:00:00\",\"end_time\":\"16:00:00\",\"start_date\":\"2026-06-20\",\"_start_date_input\":\"June 20, 2026\",\"_start_time_input\":\"11:00\",\"_end_time_input\":\"16:00\",\"isOffStart\":false},{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"11:00:00\",\"end_time\":\"16:00:00\",\"start_date\":\"2026-06-21\",\"_start_date_input\":\"June 21, 2026\",\"_start_time_input\":\"11:00\",\"_end_time_input\":\"16:00\",\"isOffStart\":false},{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"11:00:00\",\"end_time\":\"16:00:00\",\"start_date\":\"2026-06-22\",\"_start_date_input\":\"June 22, 2026\",\"_start_time_input\":\"11:00\",\"_end_time_input\":\"16:00\",\"isOffStart\":false},{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"11:00:00\",\"end_time\":\"16:00:00\",\"start_date\":\"2026-06-23\",\"_start_date_input\":\"June 23, 2026\",\"_start_time_input\":\"11:00\",\"_end_time_input\":\"16:00\",\"isOffStart\":false},{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"11:00:00\",\"end_time\":\"16:00:00\",\"start_date\":\"2026-06-24\",\"_start_date_input\":\"June 24, 2026\",\"_start_time_input\":\"11:00\",\"_end_time_input\":\"16:00\",\"isOffStart\":false},{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"11:00:00\",\"end_time\":\"16:00:00\",\"start_date\":\"2026-06-25\",\"_start_date_input\":\"June 25, 2026\",\"_start_time_input\":\"11:00\",\"_end_time_input\":\"16:00\",\"isOffStart\":false},{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"11:00:00\",\"end_time\":\"16:00:00\",\"start_date\":\"2026-06-26\",\"_start_date_input\":\"June 26, 2026\",\"_start_time_input\":\"11:00\",\"_end_time_input\":\"16:00\",\"isOffStart\":false},{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"11:00:00\",\"end_time\":\"16:00:00\",\"start_date\":\"2026-06-27\",\"_start_date_input\":\"June 27, 2026\",\"_start_time_input\":\"11:00\",\"_end_time_input\":\"16:00\",\"isOffStart\":false},{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"11:00:00\",\"end_time\":\"16:00:00\",\"start_date\":\"2026-06-28\",\"_start_date_input\":\"June 28, 2026\",\"_start_time_input\":\"11:00\",\"_end_time_input\":\"16:00\",\"isOffStart\":false},{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"11:00:00\",\"end_time\":\"16:00:00\",\"start_date\":\"2026-06-29\",\"_start_date_input\":\"June 29, 2026\",\"_start_time_input\":\"11:00\",\"_end_time_input\":\"16:00\",\"isOffStart\":false},{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"11:00:00\",\"end_time\":\"16:00:00\",\"start_date\":\"2026-06-30\",\"_start_date_input\":\"June 30, 2026\",\"_start_time_input\":\"11:00\",\"_end_time_input\":\"16:00\",\"isOffStart\":false}]","_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[861],"tribe_events_cat":[1013,1007,277,281,313,309],"class_list":["post-10017803","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-jt-feuer-en","tribe_events_cat-handwerksvorfuehrung-en","tribe_events_cat-keine-anmeldung-en","tribe_events_cat-erwachsene-en","tribe_events_cat-kinder-in-begleitung-en","tribe_events_cat-4plus-en","tribe_events_cat-mehrsprachig-en","cat_handwerksvorfuehrung-en","cat_keine-anmeldung-en","cat_erwachsene-en","cat_kinder-in-begleitung-en","cat_4plus-en","cat_mehrsprachig-en","tribe-recurring-event","tribe-recurring-event-parent"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fire making demonstration - archeoParc Schnalstal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.archeoparc.it\/en\/event\/demonstration-zum-feuermachen-wie-oetzi\/2026-05-13\/\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.archeoparc.it\\\/en\\\/event\\\/demonstration-zum-feuermachen-wie-oetzi\\\/2026-05-13\\\/\",\"url\":\"https:\\\/\\\/www.archeoparc.it\\\/en\\\/event\\\/demonstration-zum-feuermachen-wie-oetzi\\\/2026-05-13\\\/\",\"name\":\"Fire making demonstration - archeoParc Schnalstal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.archeoparc.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.archeoparc.it\\\/en\\\/event\\\/demonstration-zum-feuermachen-wie-oetzi\\\/2026-05-13\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.archeoparc.it\\\/en\\\/event\\\/demonstration-zum-feuermachen-wie-oetzi\\\/2026-05-13\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.archeoparc.it\\\/wp-content\\\/uploads\\\/archeoparc-schnalstal-25190.jpg\",\"datePublished\":\"2026-05-11T14:58:28+00:00\",\"dateModified\":\"2026-05-11T15:00:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.archeoparc.it\\\/en\\\/event\\\/demonstration-zum-feuermachen-wie-oetzi\\\/2026-05-13\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.archeoparc.it\\\/en\\\/event\\\/demonstration-zum-feuermachen-wie-oetzi\\\/2026-05-13\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.archeoparc.it\\\/en\\\/event\\\/demonstration-zum-feuermachen-wie-oetzi\\\/2026-05-13\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.archeoparc.it\\\/wp-content\\\/uploads\\\/archeoparc-schnalstal-25190.jpg\",\"contentUrl\":\"https:\\\/\\\/www.archeoparc.it\\\/wp-content\\\/uploads\\\/archeoparc-schnalstal-25190.jpg\",\"width\":1920,\"height\":1437},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.archeoparc.it\\\/en\\\/event\\\/demonstration-zum-feuermachen-wie-oetzi\\\/2026-05-13\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/www.archeoparc.it\\\/veranstaltungen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fire making demonstration\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.archeoparc.it\\\/#website\",\"url\":\"https:\\\/\\\/www.archeoparc.it\\\/\",\"name\":\"archeoParc Schnalstal\",\"description\":\"Arch\u00e4ologisches Freilichtmuseum\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.archeoparc.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.archeoparc.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.archeoparc.it\\\/#organization\",\"name\":\"archeoparc Schnalstal\",\"url\":\"https:\\\/\\\/www.archeoparc.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.archeoparc.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.archeoparc.it\\\/wp-content\\\/uploads\\\/cropped-archeoparc_logo_sw.png\",\"contentUrl\":\"https:\\\/\\\/www.archeoparc.it\\\/wp-content\\\/uploads\\\/cropped-archeoparc_logo_sw.png\",\"width\":654,\"height\":211,\"caption\":\"archeoparc Schnalstal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.archeoparc.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fire making demonstration - archeoParc Schnalstal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.archeoparc.it\/en\/event\/demonstration-zum-feuermachen-wie-oetzi\/2026-05-13\/","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.archeoparc.it\/en\/event\/demonstration-zum-feuermachen-wie-oetzi\/2026-05-13\/","url":"https:\/\/www.archeoparc.it\/en\/event\/demonstration-zum-feuermachen-wie-oetzi\/2026-05-13\/","name":"Fire making demonstration - archeoParc Schnalstal","isPartOf":{"@id":"https:\/\/www.archeoparc.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.archeoparc.it\/en\/event\/demonstration-zum-feuermachen-wie-oetzi\/2026-05-13\/#primaryimage"},"image":{"@id":"https:\/\/www.archeoparc.it\/en\/event\/demonstration-zum-feuermachen-wie-oetzi\/2026-05-13\/#primaryimage"},"thumbnailUrl":"https:\/\/www.archeoparc.it\/wp-content\/uploads\/archeoparc-schnalstal-25190.jpg","datePublished":"2026-05-11T14:58:28+00:00","dateModified":"2026-05-11T15:00:34+00:00","breadcrumb":{"@id":"https:\/\/www.archeoparc.it\/en\/event\/demonstration-zum-feuermachen-wie-oetzi\/2026-05-13\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.archeoparc.it\/en\/event\/demonstration-zum-feuermachen-wie-oetzi\/2026-05-13\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.archeoparc.it\/en\/event\/demonstration-zum-feuermachen-wie-oetzi\/2026-05-13\/#primaryimage","url":"https:\/\/www.archeoparc.it\/wp-content\/uploads\/archeoparc-schnalstal-25190.jpg","contentUrl":"https:\/\/www.archeoparc.it\/wp-content\/uploads\/archeoparc-schnalstal-25190.jpg","width":1920,"height":1437},{"@type":"BreadcrumbList","@id":"https:\/\/www.archeoparc.it\/en\/event\/demonstration-zum-feuermachen-wie-oetzi\/2026-05-13\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Veranstaltungen","item":"https:\/\/www.archeoparc.it\/veranstaltungen\/"},{"@type":"ListItem","position":2,"name":"Fire making demonstration"}]},{"@type":"WebSite","@id":"https:\/\/www.archeoparc.it\/#website","url":"https:\/\/www.archeoparc.it\/","name":"archeoParc Schnalstal","description":"Arch\u00e4ologisches Freilichtmuseum","publisher":{"@id":"https:\/\/www.archeoparc.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.archeoparc.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.archeoparc.it\/#organization","name":"archeoparc Schnalstal","url":"https:\/\/www.archeoparc.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.archeoparc.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.archeoparc.it\/wp-content\/uploads\/cropped-archeoparc_logo_sw.png","contentUrl":"https:\/\/www.archeoparc.it\/wp-content\/uploads\/cropped-archeoparc_logo_sw.png","width":654,"height":211,"caption":"archeoparc Schnalstal"},"image":{"@id":"https:\/\/www.archeoparc.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.archeoparc.it\/en\/wp-json\/wp\/v2\/tribe_events\/10017803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.archeoparc.it\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.archeoparc.it\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.archeoparc.it\/en\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":0,"href":"https:\/\/www.archeoparc.it\/en\/wp-json\/wp\/v2\/tribe_events\/10017803\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.archeoparc.it\/en\/wp-json\/wp\/v2\/media\/54100"}],"wp:attachment":[{"href":"https:\/\/www.archeoparc.it\/en\/wp-json\/wp\/v2\/media?parent=10017803"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.archeoparc.it\/en\/wp-json\/wp\/v2\/tags?post=10017803"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.archeoparc.it\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=10017803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}